{"id":7431,"date":"2026-06-23T13:49:59","date_gmt":"2026-06-23T12:49:59","guid":{"rendered":"https:\/\/colosseo-roma.it\/cookie-policy\/"},"modified":"2026-06-23T14:14:43","modified_gmt":"2026-06-23T13:14:43","slug":"cookie-policy","status":"publish","type":"page","link":"https:\/\/colosseo-roma.it\/es\/cookie-policy\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7431\" class=\"elementor elementor-7431\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d30f094 e-flex e-con-boxed e-con e-parent\" data-id=\"2d30f094\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58208f05 uppercasefont elementor-widget elementor-widget-heading\" data-id=\"58208f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cookie Policy<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43bd848c elementor-widget elementor-widget-text-editor\" data-id=\"43bd848c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<b>Ultimo aggiornamento: <\/b>23-06-2026\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511b9946 elementor-widget elementor-widget-text-editor\" data-id=\"511b9946\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"21\" data-end=\"144\">La presente Cookie Policy descrive l&#8217;utilizzo dei cookie e di tecnologie simili su questo sito web, gestito da Web Maremma.<\/p><h2 data-section-id=\"qi0iac\" data-start=\"146\" data-end=\"174\"><span role=\"text\"><strong data-start=\"149\" data-end=\"174\">1. COSA SONO I COOKIE<\/strong><\/span><\/h2><p data-start=\"176\" data-end=\"368\">I cookie sono piccoli file di testo che i siti web inviano al dispositivo dell&#8217;utente, dove vengono memorizzati e successivamente ritrasmessi agli stessi siti web durante le visite successive.<\/p><p data-start=\"370\" data-end=\"601\">I cookie vengono utilizzati per finalit\u00e0 quali l&#8217;abilitazione delle funzionalit\u00e0 del sito web, il monitoraggio delle sessioni, la memorizzazione delle preferenze dell&#8217;utente e la raccolta di informazioni statistiche e di marketing.<\/p><h2 data-section-id=\"b5tt3f\" data-start=\"603\" data-end=\"643\"><span role=\"text\"><strong data-start=\"606\" data-end=\"643\">2. TIPOLOGIE DI COOKIE UTILIZZATI<\/strong><\/span><\/h2><h3 data-section-id=\"m4vkzh\" data-start=\"645\" data-end=\"667\"><span role=\"text\"><strong data-start=\"649\" data-end=\"667\">Cookie Tecnici<\/strong><\/span><\/h3><p data-start=\"669\" data-end=\"782\">Questi cookie sono necessari per il corretto funzionamento del Sito Web e non richiedono il consenso dell&#8217;utente.<\/p><p data-start=\"784\" data-end=\"876\">Comprendono cookie di sessione, cookie per le preferenze linguistiche e cookie di sicurezza.<\/p><h3 data-section-id=\"1bk3fmm\" data-start=\"878\" data-end=\"902\"><span role=\"text\"><strong data-start=\"882\" data-end=\"902\">Cookie Analitici<\/strong><\/span><\/h3><p data-start=\"904\" data-end=\"1083\">Utilizziamo Google Analytics 4 con anonimizzazione dell&#8217;indirizzo IP e modalit\u00e0 di consenso attivata per raccogliere informazioni statistiche aggregate sull&#8217;utilizzo del Sito Web.<\/p><p data-start=\"1085\" data-end=\"1150\">Questi cookie vengono attivati solo dopo il consenso dell&#8217;utente.<\/p><h3 data-section-id=\"1aqj7h2\" data-start=\"1152\" data-end=\"1194\"><span role=\"text\"><strong data-start=\"1156\" data-end=\"1194\">Cookie di Marketing e Profilazione<\/strong><\/span><\/h3><p data-start=\"1196\" data-end=\"1371\">Utilizziamo Google Ads e Google Tag Manager per misurare le prestazioni delle campagne pubblicitarie, analizzare le conversioni e mostrare annunci pubblicitari personalizzati.<\/p><p data-start=\"1373\" data-end=\"1438\">Questi cookie vengono attivati solo dopo il consenso dell&#8217;utente.<\/p><h3 data-section-id=\"cflga5\" data-start=\"1440\" data-end=\"1469\"><span role=\"text\"><strong data-start=\"1444\" data-end=\"1469\">Cookie di Terze Parti<\/strong><\/span><\/h3><p data-start=\"1471\" data-end=\"1691\">Quando si clicca sui link che reindirizzano al nostro partner ufficiale per le prenotazioni Tiqets.com, possono essere installati cookie di tracciamento al fine di attribuire correttamente le commissioni di affiliazione.<\/p><p data-start=\"1693\" data-end=\"1788\">Tiqets agisce come titolare autonomo del trattamento per tali attivit\u00e0 di trattamento dei dati.<\/p><h2 data-section-id=\"ess60r\" data-start=\"1790\" data-end=\"1821\"><span role=\"text\"><strong data-start=\"1793\" data-end=\"1821\">3. GESTIONE DEL CONSENSO<\/strong><\/span><\/h2><p data-start=\"1823\" data-end=\"2017\">Al primo accesso al Sito Web, un banner per i cookie consente agli utenti di accettare i cookie, rifiutare i cookie non essenziali oppure personalizzare le proprie preferenze relative ai cookie.<\/p><p data-start=\"2019\" data-end=\"2135\">Il consenso ai cookie \u00e8 gestito tramite la piattaforma CookieScript in conformit\u00e0 al GDPR e alle normative ePrivacy.<\/p><p data-start=\"2137\" data-end=\"2306\">Gli utenti possono modificare o revocare il proprio consenso in qualsiasi momento tramite lo strumento di gestione del consenso o attraverso le impostazioni del browser.<\/p><h2 data-section-id=\"1emcagr\" data-start=\"2308\" data-end=\"2363\"><span role=\"text\"><strong data-start=\"2311\" data-end=\"2363\">4. DISABILITAZIONE DEI COOKIE TRAMITE IL BROWSER<\/strong><\/span><\/h2><p data-start=\"2365\" data-end=\"2547\">Gli utenti possono disabilitare i cookie direttamente tramite le impostazioni del proprio browser. Tuttavia, alcune funzionalit\u00e0 del Sito Web potrebbero non funzionare correttamente.<\/p><p data-start=\"2549\" data-end=\"2623\">Guide dei browser: Google Chrome, Mozilla Firefox, Safari, Microsoft Edge.<\/p><h2 data-section-id=\"15l3ym2\" data-start=\"2625\" data-end=\"2672\"><span role=\"text\"><strong data-start=\"2628\" data-end=\"2672\">5. MODIFICHE ALLA PRESENTE COOKIE POLICY<\/strong><\/span><\/h2><p data-start=\"2674\" data-end=\"2760\">Ci riserviamo il diritto di aggiornare la presente Cookie Policy in qualsiasi momento.<\/p><p data-start=\"2762\" data-end=\"2868\">Gli utenti sono invitati a consultare periodicamente questa pagina per verificare eventuali aggiornamenti.<\/p><p data-start=\"2870\" data-end=\"2980\" data-is-last-node=\"\" data-is-only-node=\"\">Per maggiori informazioni sul trattamento dei dati personali, si prega di consultare la nostra Privacy Policy.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La presente Cookie Policy descrive l&#8217;utilizzo dei cookie e di tecnologie simili su questo sito web, gestito da Web Maremma. 1. COSA SONO I COOKIE I cookie sono piccoli file di testo che i siti web inviano al dispositivo dell&#8217;utente, dove vengono memorizzati e successivamente ritrasmessi agli stessi siti web durante le visite successive. I [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":16,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"iawp_total_views":1,"footnotes":""},"class_list":["post-7431","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/pages\/7431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/comments?post=7431"}],"version-history":[{"count":0,"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/pages\/7431\/revisions"}],"wp:attachment":[{"href":"https:\/\/colosseo-roma.it\/es\/wp-json\/wp\/v2\/media?parent=7431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}